{"id":5213,"date":"2025-09-24T16:21:11","date_gmt":"2025-09-24T15:21:11","guid":{"rendered":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001.jpg"},"modified":"2025-09-24T16:21:11","modified_gmt":"2025-09-24T15:21:11","slug":"%d9%81%d8%a6%d8%a9-20-%d8%a8%d8%a7%d9%84%d9%85%d8%a6%d8%a9-%d9%85%d8%ad%d8%b6%d8%b1-%d8%aa%d8%b1%d8%aa%d9%8a%d8%a8%d9%8a-%d9%88-%d9%85%d9%82%d8%a8%d9%88%d9%84%d9%8a%d9%86-%d9%82%d8%b3%d9%85-%d8%a7","status":"inherit","type":"attachment","link":"https:\/\/www.univ-tebessa.dz\/fssh\/2025\/09\/24\/5191\/%d9%81%d8%a6%d8%a9-20-%d8%a8%d8%a7%d9%84%d9%85%d8%a6%d8%a9-%d9%85%d8%ad%d8%b6%d8%b1-%d8%aa%d8%b1%d8%aa%d9%8a%d8%a8%d9%8a-%d9%88-%d9%85%d9%82%d8%a8%d9%88%d9%84%d9%8a%d9%86-%d9%82%d8%b3%d9%85-%d8%a7\/","title":{"rendered":"\u0641\u064a\u0654\u0629 20 \u0628\u0627\u0644\u0645\u064a\u0654\u0629 \u0645\u062d\u0636\u0631 \u062a\u0631\u062a\u064a\u0628\u064a \u0648 \u0645\u0642\u0628\u0648\u0644\u064a\u0646 \u0642\u0633\u0645 \u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001"},"author":61,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":""},"class_list":["post-5213","attachment","type-attachment","status-inherit","hentry","entry"],"smush":{"stats":{"time":0.29000000000000004,"bytes":68538,"percent":10.8,"size_before":634336,"size_after":565798,"lossy":0,"keep_exif":0,"api_version":"1.0"},"sizes":{"medium":{"time":0.01,"bytes":580,"percent":7.31,"size_before":7930,"size_after":7350},"cmplz_banner_image":{"time":0.01,"bytes":457,"percent":7.27,"size_before":6290,"size_after":5833},"ocean-thumb-ml":{"time":0.01,"bytes":4241,"percent":9.47,"size_before":44788,"size_after":40547},"ocean-thumb-m":{"time":0.02,"bytes":3914,"percent":9.69,"size_before":40385,"size_after":36471},"1536x1536":{"time":0.03,"bytes":15971,"percent":12.38,"size_before":129025,"size_after":113054},"tileview":{"time":0.01,"bytes":1147,"percent":7.93,"size_before":14460,"size_after":13313},"gridsquare":{"time":0.02,"bytes":1191,"percent":7.73,"size_before":15416,"size_after":14225},"meccarouselthumb":{"time":0.01,"bytes":1736,"percent":8.03,"size_before":21629,"size_after":19893},"thumblist":{"time":0.01,"bytes":940,"percent":7.54,"size_before":12466,"size_after":11526},"thumbnail":{"time":0.01,"bytes":283,"percent":6.73,"size_before":4208,"size_after":3925},"wp_scaled":{"time":0.05,"bytes":13806,"percent":12.41,"size_before":111278,"size_after":97472},"ocean-thumb-l":{"time":0.05,"bytes":8420,"percent":9.73,"size_before":86553,"size_after":78133},"medium_large":{"time":0.03,"bytes":8584,"percent":11.69,"size_before":73431,"size_after":64847},"large":{"time":0.02,"bytes":7268,"percent":10.93,"size_before":66477,"size_after":59209}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-scaled.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-212x300.jpg 212w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-724x1024.jpg 724w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-768x1086.jpg 768w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-1086x1536.jpg 1086w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-scaled.jpg 990w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":990,"height":1400,"file":"2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-scaled.jpg","filesize":111278,"sizes":{"medium":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-212x300.jpg","width":212,"height":300,"filesize":7930,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-212x300.jpg"},"large":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-724x1024.jpg","width":724,"height":1024,"filesize":66477,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-724x1024.jpg"},"thumbnail":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-150x150.jpg","width":150,"height":150,"filesize":4208,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-150x150.jpg"},"medium_large":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-768x1086.jpg","width":768,"height":1086,"filesize":73431,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-768x1086.jpg"},"thumblist":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-300x300.jpg","width":300,"height":300,"filesize":12466,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-300x300.jpg"},"meccarouselthumb":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-474x324.jpg","width":474,"height":324,"filesize":21629,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-474x324.jpg"},"gridsquare":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-391x260.jpg","width":391,"height":260,"filesize":15416,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-391x260.jpg"},"tileview":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-300x400.jpg","width":300,"height":400,"filesize":14460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-300x400.jpg"},"1536x1536":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-1086x1536.jpg","width":1086,"height":1536,"filesize":129025,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-1086x1536.jpg"},"ocean-thumb-m":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-600x600.jpg","width":600,"height":600,"filesize":40385,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-600x600.jpg"},"ocean-thumb-ml":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-800x450.jpg","width":800,"height":450,"filesize":44788,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-800x450.jpg"},"ocean-thumb-l":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-1200x700.jpg","width":1200,"height":700,"filesize":86553,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-1200x700.jpg"},"cmplz_banner_image":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-350x100.jpg","width":350,"height":100,"filesize":6290,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-350x100.jpg"},"full":{"file":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-scaled.jpg","width":990,"height":1400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001.jpg"},"post":5191,"source_url":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/09\/\u0641\u0626\u0629-20-\u0628\u0627\u0644\u0645\u0626\u0629-\u0645\u062d\u0636\u0631-\u062a\u0631\u062a\u064a\u0628\u064a-\u0648-\u0645\u0642\u0628\u0648\u0644\u064a\u0646-\u0642\u0633\u0645-\u0627\u0644\u0641\u0644\u0633\u0641\u0629_page-0001-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/media\/5213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/comments?post=5213"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":5191,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/posts\/5191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}