{"id":3128,"date":"2023-10-17T13:39:47","date_gmt":"2023-10-17T12:39:47","guid":{"rendered":"https:\/\/www.univ-tebessa.dz\/fssh\/?p=3128"},"modified":"2023-10-17T13:51:46","modified_gmt":"2023-10-17T12:51:46","slug":"%d9%88%d9%82%d9%81%d8%a9-%d8%aa%d8%b1%d8%ad%d9%85-%d8%aa%d8%ae%d9%84%d9%8a%d8%af%d8%a7-%d9%84%d8%a3%d8%b1%d9%88%d8%a7%d8%ad-%d8%b4%d9%87%d8%af%d8%a7%d8%a1-%d9%85%d8%ac%d8%a7%d8%b2%d8%b1-17%d8%a3","status":"publish","type":"post","link":"https:\/\/www.univ-tebessa.dz\/fssh\/2023\/10\/17\/%d9%88%d9%82%d9%81%d8%a9-%d8%aa%d8%b1%d8%ad%d9%85-%d8%aa%d8%ae%d9%84%d9%8a%d8%af%d8%a7-%d9%84%d8%a3%d8%b1%d9%88%d8%a7%d8%ad-%d8%b4%d9%87%d8%af%d8%a7%d8%a1-%d9%85%d8%ac%d8%a7%d8%b2%d8%b1-17%d8%a3\/","title":{"rendered":"\u0648\u0642\u0641\u0629 \u062a\u0631\u062d\u0645 \u062a\u062e\u0644\u064a\u062f\u0627 \u0644\u0623\u0631\u0648\u0627\u062d \u0634\u0647\u062f\u0627\u0621  \u0645\u062c\u0627\u0632\u0631 17\u0623\u0643\u062a\u0648\u0628\u0631 1961 \u060c\u0648\u0643\u0630\u0627  \u0625\u062d\u064a\u0627\u0621 \u0644\u0644\u064a\u0648\u0645 \u0627\u0644\u0648\u0637\u0646\u064a \u0644\u0644\u0647\u062c\u0631\u0629  \u0648\u062a\u0623\u062a\u064a \u0647\u0630\u0647 \u0627\u0644\u0648\u0641\u0642\u0629 \u062a\u0646\u0641\u064a\u0630\u0627 \u0644\u0642\u0631\u0627\u0631 \u0631\u0626\u064a\u0633 \u0627\u0644\u062c\u0645\u0647\u0648\u0631\u064a\u0629 \u0627\u0644\u0633\u064a\u062f \u0639\u0628\u062f \u0627\u0644\u0645\u062c\u064a\u062f \u062a\u0628\u0648\u0646"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-3128 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2023\/10\/17\/%d9%88%d9%82%d9%81%d8%a9-%d8%aa%d8%b1%d8%ad%d9%85-%d8%aa%d8%ae%d9%84%d9%8a%d8%af%d8%a7-%d9%84%d8%a3%d8%b1%d9%88%d8%a7%d8%ad-%d8%b4%d9%87%d8%af%d8%a7%d8%a1-%d9%85%d8%ac%d8%a7%d8%b2%d8%b1-17%d8%a3\/img20231017111037\/'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111037-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111037-300x225.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111037-1024x768.jpg 1024w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111037-768x576.jpg 768w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111037-1536x1152.jpg 1536w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111037-2048x1536.jpg 2048w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111037-scaled.jpg 1400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-2' class='gallery galleryid-3128 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2023\/10\/17\/%d9%88%d9%82%d9%81%d8%a9-%d8%aa%d8%b1%d8%ad%d9%85-%d8%aa%d8%ae%d9%84%d9%8a%d8%af%d8%a7-%d9%84%d8%a3%d8%b1%d9%88%d8%a7%d8%ad-%d8%b4%d9%87%d8%af%d8%a7%d8%a1-%d9%85%d8%ac%d8%a7%d8%b2%d8%b1-17%d8%a3\/img20231017110903\/'><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110903-300x225.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110903-300x225.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110903-1024x768.jpg 1024w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110903-768x576.jpg 768w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110903-1536x1152.jpg 1536w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110903-2048x1536.jpg 2048w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110903-scaled.jpg 1400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2023\/10\/17\/%d9%88%d9%82%d9%81%d8%a9-%d8%aa%d8%b1%d8%ad%d9%85-%d8%aa%d8%ae%d9%84%d9%8a%d8%af%d8%a7-%d9%84%d8%a3%d8%b1%d9%88%d8%a7%d8%ad-%d8%b4%d9%87%d8%af%d8%a7%d8%a1-%d9%85%d8%ac%d8%a7%d8%b2%d8%b1-17%d8%a3\/img20231017110929\/'><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110929-300x225.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110929-300x225.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110929-1024x768.jpg 1024w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110929-768x576.jpg 768w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110929-1536x1152.jpg 1536w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110929-2048x1536.jpg 2048w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110929-scaled.jpg 1400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2023\/10\/17\/%d9%88%d9%82%d9%81%d8%a9-%d8%aa%d8%b1%d8%ad%d9%85-%d8%aa%d8%ae%d9%84%d9%8a%d8%af%d8%a7-%d9%84%d8%a3%d8%b1%d9%88%d8%a7%d8%ad-%d8%b4%d9%87%d8%af%d8%a7%d8%a1-%d9%85%d8%ac%d8%a7%d8%b2%d8%b1-17%d8%a3\/img20231017110937\/'><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110937-300x225.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110937-300x225.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110937-1024x768.jpg 1024w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110937-768x576.jpg 768w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110937-1536x1152.jpg 1536w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110937-2048x1536.jpg 2048w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110937-scaled.jpg 1400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2023\/10\/17\/%d9%88%d9%82%d9%81%d8%a9-%d8%aa%d8%b1%d8%ad%d9%85-%d8%aa%d8%ae%d9%84%d9%8a%d8%af%d8%a7-%d9%84%d8%a3%d8%b1%d9%88%d8%a7%d8%ad-%d8%b4%d9%87%d8%af%d8%a7%d8%a1-%d9%85%d8%ac%d8%a7%d8%b2%d8%b1-17%d8%a3\/img20231017111019\/'><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111019-300x225.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111019-300x225.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111019-1024x768.jpg 1024w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111019-768x576.jpg 768w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111019-1536x1152.jpg 1536w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111019-2048x1536.jpg 2048w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111019-scaled.jpg 1400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2023\/10\/17\/%d9%88%d9%82%d9%81%d8%a9-%d8%aa%d8%b1%d8%ad%d9%85-%d8%aa%d8%ae%d9%84%d9%8a%d8%af%d8%a7-%d9%84%d8%a3%d8%b1%d9%88%d8%a7%d8%ad-%d8%b4%d9%87%d8%af%d8%a7%d8%a1-%d9%85%d8%ac%d8%a7%d8%b2%d8%b1-17%d8%a3\/img20231017111316\/'><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111316-300x225.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111316-300x225.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111316-1024x768.jpg 1024w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111316-768x576.jpg 768w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111316-1536x1152.jpg 1536w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111316-2048x1536.jpg 2048w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111316-scaled.jpg 1400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2023\/10\/17\/%d9%88%d9%82%d9%81%d8%a9-%d8%aa%d8%b1%d8%ad%d9%85-%d8%aa%d8%ae%d9%84%d9%8a%d8%af%d8%a7-%d9%84%d8%a3%d8%b1%d9%88%d8%a7%d8%ad-%d8%b4%d9%87%d8%af%d8%a7%d8%a1-%d9%85%d8%ac%d8%a7%d8%b2%d8%b1-17%d8%a3\/img20231017110921\/'><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110921-300x225.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110921-300x225.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110921-1024x768.jpg 1024w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110921-768x576.jpg 768w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110921-1536x1152.jpg 1536w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110921-2048x1536.jpg 2048w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110921-scaled.jpg 1400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2023\/10\/17\/%d9%88%d9%82%d9%81%d8%a9-%d8%aa%d8%b1%d8%ad%d9%85-%d8%aa%d8%ae%d9%84%d9%8a%d8%af%d8%a7-%d9%84%d8%a3%d8%b1%d9%88%d8%a7%d8%ad-%d8%b4%d9%87%d8%af%d8%a7%d8%a1-%d9%85%d8%ac%d8%a7%d8%b2%d8%b1-17%d8%a3\/img20231017111103\/'><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111103-300x225.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111103-300x225.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111103-1024x768.jpg 1024w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111103-768x576.jpg 768w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111103-1536x1152.jpg 1536w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111103-2048x1536.jpg 2048w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017111103-scaled.jpg 1400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2023\/10\/17\/%d9%88%d9%82%d9%81%d8%a9-%d8%aa%d8%b1%d8%ad%d9%85-%d8%aa%d8%ae%d9%84%d9%8a%d8%af%d8%a7-%d9%84%d8%a3%d8%b1%d9%88%d8%a7%d8%ad-%d8%b4%d9%87%d8%af%d8%a7%d8%a1-%d9%85%d8%ac%d8%a7%d8%b2%d8%b1-17%d8%a3\/img20231017110813\/'><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110813-300x225.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110813-300x225.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110813-1024x768.jpg 1024w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110813-768x576.jpg 768w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110813-1536x1152.jpg 1536w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110813-2048x1536.jpg 2048w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2023\/10\/IMG20231017110813-scaled.jpg 1400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":55,"featured_media":3138,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1","entry","has-media"],"_links":{"self":[{"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/posts\/3128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/comments?post=3128"}],"version-history":[{"count":3,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/posts\/3128\/revisions"}],"predecessor-version":[{"id":3145,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/posts\/3128\/revisions\/3145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/media\/3138"}],"wp:attachment":[{"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/media?parent=3128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/categories?post=3128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/tags?post=3128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}