{"id":4968,"date":"2025-06-03T10:09:55","date_gmt":"2025-06-03T09:09:55","guid":{"rendered":"https:\/\/www.univ-tebessa.dz\/fssh\/?p=4968"},"modified":"2025-06-03T10:09:55","modified_gmt":"2025-06-03T09:09:55","slug":"%d8%a5%d9%86%d8%aa%d8%ae%d8%a7%d8%a8%d8%a7%d8%aa-%d8%aa%d8%ac%d8%af%d9%8a%d8%af-%d8%a7%d9%84%d8%b9%d8%b6%d9%88%d9%8a%d8%a9-%d9%81%d9%8a-%d9%85%d8%ac%d9%84%d8%b3-%d8%a5%d8%af%d8%a7%d8%b1%d8%a9-%d9%83","status":"publish","type":"post","link":"https:\/\/www.univ-tebessa.dz\/fssh\/2025\/06\/03\/%d8%a5%d9%86%d8%aa%d8%ae%d8%a7%d8%a8%d8%a7%d8%aa-%d8%aa%d8%ac%d8%af%d9%8a%d8%af-%d8%a7%d9%84%d8%b9%d8%b6%d9%88%d9%8a%d8%a9-%d9%81%d9%8a-%d9%85%d8%ac%d9%84%d8%b3-%d8%a5%d8%af%d8%a7%d8%b1%d8%a9-%d9%83\/","title":{"rendered":"\u0625\u0646\u062a\u062e\u0627\u0628\u0627\u062a \u062a\u062c\u062f\u064a\u062f \u0627\u0644\u0639\u0636\u0648\u064a\u0629 \u0641\u064a \u0645\u062c\u0644\u0633 \u0625\u062f\u0627\u0631\u0629 \u0643\u0644\u064a\u0629 \u0627\u0644\u0639\u0644\u0648\u0645 \u0627\u0644\u0625\u0646\u0633\u0627\u0646\u064a\u0629 \u0648 \u0627\u0644\u0625\u062c\u062a\u0645\u0627\u0639\u064a\u0629"},"content":{"rendered":"<p><span style=\"font-size: 18pt\">\u062a\u0645 \u0635\u0628\u0627\u062d \u0627\u0644\u064a\u0648\u0645 \u0627\u0644\u062b\u0644\u0627\u062b\u0627\u0621 3 \u062c\u0648\u0627\u0646 2025 \u0639\u0644\u0649 \u0627\u0644\u0633\u0627\u0639\u0629 9 \u0635\u0628\u0627\u062d\u0627 \u0625\u0646\u062a\u062e\u0627\u0628\u0627\u062a \u062a\u062c\u062f\u064a\u062f \u0627\u0644\u0639\u0636\u0648\u064a\u0629 \u0641\u064a \u0645\u062c\u0644\u0633 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0643\u0644\u064a\u0629 \u0633\u0644\u0643 \u0627\u0644\u0623\u0633\u0627\u062a\u0630\u0629 \u0627\u0644\u0645\u062d\u0627\u0636\u0631\u064a\u0646 \u0642\u0633\u0645\u064a \u0623<\/span><div id='gallery-1' class='gallery galleryid-4968 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2025\/06\/03\/%d8%a5%d9%86%d8%aa%d8%ae%d8%a7%d8%a8%d8%a7%d8%aa-%d8%aa%d8%ac%d8%af%d9%8a%d8%af-%d8%a7%d9%84%d8%b9%d8%b6%d9%88%d9%8a%d8%a9-%d9%81%d9%8a-%d9%85%d8%ac%d9%84%d8%b3-%d8%a5%d8%af%d8%a7%d8%b1%d8%a9-%d9%83\/attachment\/1000193378\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193378-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193378-150x150.jpg 150w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193378-300x300.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193378-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2025\/06\/03\/%d8%a5%d9%86%d8%aa%d8%ae%d8%a7%d8%a8%d8%a7%d8%aa-%d8%aa%d8%ac%d8%af%d9%8a%d8%af-%d8%a7%d9%84%d8%b9%d8%b6%d9%88%d9%8a%d8%a9-%d9%81%d9%8a-%d9%85%d8%ac%d9%84%d8%b3-%d8%a5%d8%af%d8%a7%d8%b1%d8%a9-%d9%83\/attachment\/1000193383\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193383-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193383-150x150.jpg 150w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193383-300x300.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193383-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2025\/06\/03\/%d8%a5%d9%86%d8%aa%d8%ae%d8%a7%d8%a8%d8%a7%d8%aa-%d8%aa%d8%ac%d8%af%d9%8a%d8%af-%d8%a7%d9%84%d8%b9%d8%b6%d9%88%d9%8a%d8%a9-%d9%81%d9%8a-%d9%85%d8%ac%d9%84%d8%b3-%d8%a5%d8%af%d8%a7%d8%b1%d8%a9-%d9%83\/attachment\/1000193380\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193380-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193380-150x150.jpg 150w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193380-300x300.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193380-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2025\/06\/03\/%d8%a5%d9%86%d8%aa%d8%ae%d8%a7%d8%a8%d8%a7%d8%aa-%d8%aa%d8%ac%d8%af%d9%8a%d8%af-%d8%a7%d9%84%d8%b9%d8%b6%d9%88%d9%8a%d8%a9-%d9%81%d9%8a-%d9%85%d8%ac%d9%84%d8%b3-%d8%a5%d8%af%d8%a7%d8%b1%d8%a9-%d9%83\/1000193384-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193384-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193384-1-150x150.jpg 150w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193384-1-300x300.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193384-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2025\/06\/03\/%d8%a5%d9%86%d8%aa%d8%ae%d8%a7%d8%a8%d8%a7%d8%aa-%d8%aa%d8%ac%d8%af%d9%8a%d8%af-%d8%a7%d9%84%d8%b9%d8%b6%d9%88%d9%8a%d8%a9-%d9%81%d9%8a-%d9%85%d8%ac%d9%84%d8%b3-%d8%a5%d8%af%d8%a7%d8%b1%d8%a9-%d9%83\/attachment\/1000193382\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193382-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193382-150x150.jpg 150w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193382-300x300.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193382-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.univ-tebessa.dz\/fssh\/2025\/06\/03\/%d8%a5%d9%86%d8%aa%d8%ae%d8%a7%d8%a8%d8%a7%d8%aa-%d8%aa%d8%ac%d8%af%d9%8a%d8%af-%d8%a7%d9%84%d8%b9%d8%b6%d9%88%d9%8a%d8%a9-%d9%81%d9%8a-%d9%85%d8%ac%d9%84%d8%b3-%d8%a5%d8%af%d8%a7%d8%b1%d8%a9-%d9%83\/attachment\/1000193381\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193381-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193381-150x150.jpg 150w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193381-300x300.jpg 300w, https:\/\/www.univ-tebessa.dz\/fssh\/wp-content\/uploads\/sites\/17\/2025\/06\/1000193381-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062a\u0645 \u0635\u0628\u0627\u062d \u0627\u0644\u064a\u0648\u0645 \u0627\u0644\u062b\u0644\u0627\u062b\u0627\u0621 3 \u062c\u0648\u0627\u0646 2025 \u0639\u0644\u0649 \u0627\u0644\u0633\u0627\u0639\u0629 9 \u0635\u0628\u0627\u062d\u0627 \u0625\u0646\u062a\u062e\u0627\u0628\u0627\u062a \u062a\u062c\u062f\u064a\u062f \u0627\u0644\u0639\u0636\u0648\u064a\u0629 \u0641\u064a \u0645\u062c\u0644\u0633 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0643\u0644\u064a\u0629 \u0633\u0644\u0643 \u0627\u0644\u0623\u0633\u0627\u062a\u0630\u0629 \u0627\u0644\u0645\u062d\u0627\u0636\u0631\u064a\u0646 \u0642\u0633\u0645\u064a \u0623<\/p>\n","protected":false},"author":61,"featured_media":4782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1","entry","has-media"],"_links":{"self":[{"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/posts\/4968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/comments?post=4968"}],"version-history":[{"count":2,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/posts\/4968\/revisions"}],"predecessor-version":[{"id":4982,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/posts\/4968\/revisions\/4982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/media\/4782"}],"wp:attachment":[{"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/media?parent=4968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/categories?post=4968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/fssh\/wp-json\/wp\/v2\/tags?post=4968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}