{"id":3771,"date":"2024-02-29T08:53:44","date_gmt":"2024-02-29T08:53:44","guid":{"rendered":"https:\/\/www.univ-tebessa.dz\/vrre\/?p=3771"},"modified":"2024-02-29T08:53:44","modified_gmt":"2024-02-29T08:53:44","slug":"offre-de-bourses-detudes-postuniversitaires-du-bureau-des-nations-unis-pour-les-affaires-spatiales-2","status":"publish","type":"post","link":"https:\/\/www.univ-tebessa.dz\/vrre\/3771\/","title":{"rendered":"Offre de bourses d\u2019\u00e9tudes postuniversitaires du bureau des Nations Unis pour les affaires spatiales"},"content":{"rendered":"<p style=\"text-align: center\"><strong>Objet: Offre de bourses d\u2019\u00e9tudes postuniversitaires du bureau des Nations Unis pour les affaires spatiales<\/strong><\/p>\n<p style=\"text-align: left\">J\u2019ai l\u2019honneur de vous informer que le Minist\u00e8re de l\u2019enseignement sup\u00e9rieur et de la recherche scientifique est destinataire d\u2019une offre de six (06) bourses d\u2019\u00e9tudes postuniversitaire sur les technologies des nano satellites, \u00e9manant du bureau des Nations Unis pour les affaires Spatiales (UNOOSA) et le gouvernement du Japon en coop\u00e9ration avec l\u2019institut de technologie de Kyushu . Les bourses sont r\u00e9parties comme suit<\/p>\n<p style=\"text-align: left\">\u00a0&#8211; Trois (03) bourses pour le programme de master<\/p>\n<p style=\"text-align: left\">\u00a0&#8211; Trois (03) bourses pour le programme de doctorat<\/p>\n<p style=\"text-align: left\">\u00a0 \u00a0Cette offre de bourses s\u2019inscrit dans le cadre du programme postuniversitaire sur les technologies des nano satellites (PNST) relevant de l\u2019initiative \u00ab Acc\u00e8s \u00e0 l\u2019espace pour tous \u00bb<\/p>\n<p style=\"text-align: left\">\u00a0Le programme couvre les frais de scolarit\u00e9 et offre une allocation destin\u00e9e \u00e0 couvrir les frais de subsistance<\/p>\n<p style=\"text-align: left\">\u00a0La date limite pour la soumission de candidature est le 05 janvier 2024. La candidature de femmes est encourag\u00e9e<\/p>\n<p style=\"text-align: left\">\u00a0Des informations compl\u00e9mentaires sont disponibles \u00e0 l\u2019adresse: <a href=\"https:\/\/www.unoosa.org\/oosa\/en\/ourwork\/access2space4all\/PNST\/PNST%20_Rounds.html\"><strong>https:\/\/www.unoosa.org\/oosa\/en\/ourwork\/access2space4all\/PNST\/PNST _Rounds.html<\/strong><\/a><\/p>\n<p style=\"text-align: left\">\u00a0Je vous saurai gr\u00e9 de bien vouloir proc\u00e9der \u00e0 une large diffusion de ce programme de bourses aupr\u00e8s de tous les \u00e9tablissements universitaires<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Objet: Offre de bourses d\u2019\u00e9tudes postuniversitaires du bureau des Nations Unis pour les affaires spatiales J\u2019ai l\u2019honneur de vous informer que le Minist\u00e8re de l\u2019enseignement sup\u00e9rieur et de la recherche scientifique est destinataire d\u2019une offre de six (06) bourses d\u2019\u00e9tudes postuniversitaire sur les technologies des nano satellites, \u00e9manant du bureau des Nations Unis pour les affaires Spatiales (UNOOSA) et le gouvernement du Japon en coop\u00e9ration avec l\u2019institut de technologie de Kyushu . Les bourses sont r\u00e9parties comme suit \u00a0&#8211; Trois (03) bourses pour le programme de master \u00a0&#8211; Trois (03) bourses pour le programme de doctorat \u00a0 \u00a0Cette offre de bourses s\u2019inscrit dans le cadre du programme postuniversitaire sur les technologies des nano satellites (PNST) relevant de l\u2019initiative \u00ab Acc\u00e8s \u00e0 l\u2019espace pour tous \u00bb \u00a0Le programme couvre les frais de scolarit\u00e9 et offre une allocation destin\u00e9e \u00e0 couvrir les frais de subsistance \u00a0La date limite pour la soumission de candidature est le 05 janvier 2024. La candidature de femmes est encourag\u00e9e \u00a0Des informations compl\u00e9mentaires sont disponibles \u00e0 l\u2019adresse: https:\/\/www.unoosa.org\/oosa\/en\/ourwork\/access2space4all\/PNST\/PNST _Rounds.html \u00a0Je vous saurai gr\u00e9 de bien vouloir proc\u00e9der \u00e0 une large diffusion de ce programme de bourses aupr\u00e8s de tous les \u00e9tablissements universitaires<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1,23,3],"tags":[],"class_list":["post-3771","post","type-post","status-publish","format-standard","hentry","category-1","category-23","category-3","entry"],"_links":{"self":[{"href":"https:\/\/www.univ-tebessa.dz\/vrre\/wp-json\/wp\/v2\/posts\/3771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univ-tebessa.dz\/vrre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.univ-tebessa.dz\/vrre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/vrre\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/vrre\/wp-json\/wp\/v2\/comments?post=3771"}],"version-history":[{"count":1,"href":"https:\/\/www.univ-tebessa.dz\/vrre\/wp-json\/wp\/v2\/posts\/3771\/revisions"}],"predecessor-version":[{"id":3772,"href":"https:\/\/www.univ-tebessa.dz\/vrre\/wp-json\/wp\/v2\/posts\/3771\/revisions\/3772"}],"wp:attachment":[{"href":"https:\/\/www.univ-tebessa.dz\/vrre\/wp-json\/wp\/v2\/media?parent=3771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/vrre\/wp-json\/wp\/v2\/categories?post=3771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.univ-tebessa.dz\/vrre\/wp-json\/wp\/v2\/tags?post=3771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}